{"id":4652,"date":"2020-11-02T21:37:20","date_gmt":"2020-11-02T19:37:20","guid":{"rendered":"http:\/\/www.ff-weppersdorf.at\/web\/?p=4652"},"modified":"2020-11-04T21:40:07","modified_gmt":"2020-11-04T19:40:07","slug":"20201102-dieselaustritt","status":"publish","type":"post","link":"https:\/\/www.ff-weppersdorf.at\/web\/20201102-dieselaustritt\/","title":{"rendered":"Diesel ausgelaufen"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 hundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-overflow:visible;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_3_4 3_4 fusion-three-fourth fusion-column-first\" style=\"--awb-bg-size:cover;width:74%; margin-right: 4%;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-title title fusion-title-1 fusion-title-text fusion-title-size-three\" style=\"--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h3 class=\"fusion-title-heading title-heading-left\" style=\"margin:0;\">Technischer Einsatz:<\/h3><span class=\"awb-title-spacer\"><\/span><div class=\"title-sep-container\"><div class=\"title-sep sep-double sep-solid\" style=\"border-color:#e0dede;\"><\/div><\/div><\/div><div class=\"fusion-text fusion-text-1\"><p>Am 2. November kam es in Weppersdorf zu einem Dieselaustritt in der Feldgasse. Die Feuerwehr wurde gebeten, den ausgetretenen Kraftstoff zu binden. Dies wurde mittels \u00d6lbindemittel erledigt, sodass die Fahrbahn anschlie\u00dfend wieder problemfrei befahren werden konnte.<\/p>\n<\/div><div class=\"fusion-title title fusion-title-2 fusion-title-text fusion-title-size-three\" style=\"--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h3 class=\"fusion-title-heading title-heading-left\" style=\"margin:0;\">Bilder<\/h3><span class=\"awb-title-spacer\"><\/span><div class=\"title-sep-container\"><div class=\"title-sep sep-double sep-solid\" style=\"border-color:#e0dede;\"><\/div><\/div><\/div><div class=\"fusion-text fusion-text-2\"><p><em>&#8211; keine Bilder vorhanden &#8211;<\/em><\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_4 1_4 fusion-one-fourth fusion-column-last\" style=\"--awb-bg-size:cover;width:22%;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-title title fusion-title-3 fusion-title-text fusion-title-size-three\" style=\"--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h3 class=\"fusion-title-heading title-heading-left\" style=\"margin:0;\">Einsatzdaten<\/h3><span class=\"awb-title-spacer\"><\/span><div class=\"title-sep-container\"><div class=\"title-sep sep-double sep-solid\" style=\"border-color:#e0dede;\"><\/div><\/div><\/div><div class=\"fusion-text fusion-text-3\"><p>Einsatznummer: <strong>#035\/2020<\/strong><\/p>\n<p>Datum: <strong>02.11.2020<\/strong><br \/>\nUhrzeit:<strong> 13:33<\/strong><\/p>\n<p>Alarmierung:\u00a0<strong>Telefonisch<\/strong><\/p>\n<p>Einsatzort: <b>Feldgasse, Weppersdorf<br \/>\n<\/b>Fahrzeuge: <strong>SOF<br \/>\n<\/strong>Mannschaft: <strong>1 <\/strong><strong>Mitglied<\/strong><\/p>\n<p>weitere Einsatzkr\u00e4fte:\u00a0<strong>&#8211;<\/strong><\/p>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;width:100%;\"><div class=\"fusion-separator-border sep-shadow\" style=\"--awb-height:20px;--awb-amount:20px;background:radial-gradient(ellipse at 50% -50% , #e0dede 0px, rgba(255, 255, 255, 0) 80%) repeat scroll 0 0 rgba(0, 0, 0, 0);background:-webkit-radial-gradient(ellipse at 50% -50% , #e0dede 0px, rgba(255, 255, 255, 0) 80%) repeat scroll 0 0 rgba(0, 0, 0, 0);background:-moz-radial-gradient(ellipse at 50% -50% , #e0dede 0px, rgba(255, 255, 255, 0) 80%) repeat scroll 0 0 rgba(0, 0, 0, 0);background:-o-radial-gradient(ellipse at 50% -50% , #e0dede 0px, rgba(255, 255, 255, 0) 80%) repeat scroll 0 0 rgba(0, 0, 0, 0);\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":3925,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"footnotes":""},"categories":[27],"tags":[],"class_list":["post-4652","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-einsaetze-2020","post_format-post-format-gallery"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Diesel ausgelaufen - Freiwillige Feuerwehr Weppersdorf<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ff-weppersdorf.at\/web\/20201102-dieselaustritt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diesel ausgelaufen - Freiwillige Feuerwehr Weppersdorf\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ff-weppersdorf.at\/web\/20201102-dieselaustritt\/\" \/>\n<meta property=\"og:site_name\" content=\"Freiwillige Feuerwehr Weppersdorf\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ff.weppersdorf\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-02T19:37:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-04T19:40:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ff-weppersdorf.at\/web\/wp-content\/uploads\/2019\/07\/hlgkuh.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jacob Schumann\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jacob Schumann\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ff-weppersdorf.at\\\/web\\\/20201102-dieselaustritt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ff-weppersdorf.at\\\/web\\\/20201102-dieselaustritt\\\/\"},\"author\":{\"name\":\"Jacob Schumann\",\"@id\":\"https:\\\/\\\/www.ff-weppersdorf.at\\\/web\\\/#\\\/schema\\\/person\\\/2580e5c26fdcda22b03944caeac2b379\"},\"headline\":\"Diesel ausgelaufen\",\"datePublished\":\"2020-11-02T19:37:20+00:00\",\"dateModified\":\"2020-11-04T19:40:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ff-weppersdorf.at\\\/web\\\/20201102-dieselaustritt\\\/\"},\"wordCount\":426,\"image\":{\"@id\":\"https:\\\/\\\/www.ff-weppersdorf.at\\\/web\\\/20201102-dieselaustritt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ff-weppersdorf.at\\\/web\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/hlgkuh.jpg\",\"articleSection\":[\"Eins\u00e4tze 2020\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ff-weppersdorf.at\\\/web\\\/20201102-dieselaustritt\\\/\",\"url\":\"https:\\\/\\\/www.ff-weppersdorf.at\\\/web\\\/20201102-dieselaustritt\\\/\",\"name\":\"Diesel ausgelaufen - Freiwillige Feuerwehr Weppersdorf\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ff-weppersdorf.at\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ff-weppersdorf.at\\\/web\\\/20201102-dieselaustritt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ff-weppersdorf.at\\\/web\\\/20201102-dieselaustritt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ff-weppersdorf.at\\\/web\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/hlgkuh.jpg\",\"datePublished\":\"2020-11-02T19:37:20+00:00\",\"dateModified\":\"2020-11-04T19:40:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ff-weppersdorf.at\\\/web\\\/#\\\/schema\\\/person\\\/2580e5c26fdcda22b03944caeac2b379\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ff-weppersdorf.at\\\/web\\\/20201102-dieselaustritt\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ff-weppersdorf.at\\\/web\\\/20201102-dieselaustritt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.ff-weppersdorf.at\\\/web\\\/20201102-dieselaustritt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ff-weppersdorf.at\\\/web\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/hlgkuh.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ff-weppersdorf.at\\\/web\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/hlgkuh.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ff-weppersdorf.at\\\/web\\\/20201102-dieselaustritt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.ff-weppersdorf.at\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Diesel ausgelaufen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ff-weppersdorf.at\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/www.ff-weppersdorf.at\\\/web\\\/\",\"name\":\"Freiwillige Feuerwehr Weppersdorf\",\"description\":\"News, Eins\u00e4tze &amp; Infos rund um die Freiwillige Feuerwehr Weppersdorf\",\"alternateName\":\"FF Weppersdorf\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ff-weppersdorf.at\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ff-weppersdorf.at\\\/web\\\/#\\\/schema\\\/person\\\/2580e5c26fdcda22b03944caeac2b379\",\"name\":\"Jacob Schumann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ccaedcfa723205f94f72eb0bd89f8aa426db1f79d3055677333d65c78074d459?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ccaedcfa723205f94f72eb0bd89f8aa426db1f79d3055677333d65c78074d459?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ccaedcfa723205f94f72eb0bd89f8aa426db1f79d3055677333d65c78074d459?s=96&d=mm&r=g\",\"caption\":\"Jacob Schumann\"},\"url\":\"https:\\\/\\\/www.ff-weppersdorf.at\\\/web\\\/author\\\/jacob\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Diesel ausgelaufen - Freiwillige Feuerwehr Weppersdorf","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ff-weppersdorf.at\/web\/20201102-dieselaustritt\/","og_locale":"de_DE","og_type":"article","og_title":"Diesel ausgelaufen - Freiwillige Feuerwehr Weppersdorf","og_url":"https:\/\/www.ff-weppersdorf.at\/web\/20201102-dieselaustritt\/","og_site_name":"Freiwillige Feuerwehr Weppersdorf","article_publisher":"https:\/\/www.facebook.com\/ff.weppersdorf\/","article_published_time":"2020-11-02T19:37:20+00:00","article_modified_time":"2020-11-04T19:40:07+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.ff-weppersdorf.at\/web\/wp-content\/uploads\/2019\/07\/hlgkuh.jpg","type":"image\/jpeg"}],"author":"Jacob Schumann","twitter_misc":{"Verfasst von":"Jacob Schumann","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ff-weppersdorf.at\/web\/20201102-dieselaustritt\/#article","isPartOf":{"@id":"https:\/\/www.ff-weppersdorf.at\/web\/20201102-dieselaustritt\/"},"author":{"name":"Jacob Schumann","@id":"https:\/\/www.ff-weppersdorf.at\/web\/#\/schema\/person\/2580e5c26fdcda22b03944caeac2b379"},"headline":"Diesel ausgelaufen","datePublished":"2020-11-02T19:37:20+00:00","dateModified":"2020-11-04T19:40:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ff-weppersdorf.at\/web\/20201102-dieselaustritt\/"},"wordCount":426,"image":{"@id":"https:\/\/www.ff-weppersdorf.at\/web\/20201102-dieselaustritt\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ff-weppersdorf.at\/web\/wp-content\/uploads\/2019\/07\/hlgkuh.jpg","articleSection":["Eins\u00e4tze 2020"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.ff-weppersdorf.at\/web\/20201102-dieselaustritt\/","url":"https:\/\/www.ff-weppersdorf.at\/web\/20201102-dieselaustritt\/","name":"Diesel ausgelaufen - Freiwillige Feuerwehr Weppersdorf","isPartOf":{"@id":"https:\/\/www.ff-weppersdorf.at\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ff-weppersdorf.at\/web\/20201102-dieselaustritt\/#primaryimage"},"image":{"@id":"https:\/\/www.ff-weppersdorf.at\/web\/20201102-dieselaustritt\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ff-weppersdorf.at\/web\/wp-content\/uploads\/2019\/07\/hlgkuh.jpg","datePublished":"2020-11-02T19:37:20+00:00","dateModified":"2020-11-04T19:40:07+00:00","author":{"@id":"https:\/\/www.ff-weppersdorf.at\/web\/#\/schema\/person\/2580e5c26fdcda22b03944caeac2b379"},"breadcrumb":{"@id":"https:\/\/www.ff-weppersdorf.at\/web\/20201102-dieselaustritt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ff-weppersdorf.at\/web\/20201102-dieselaustritt\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.ff-weppersdorf.at\/web\/20201102-dieselaustritt\/#primaryimage","url":"https:\/\/www.ff-weppersdorf.at\/web\/wp-content\/uploads\/2019\/07\/hlgkuh.jpg","contentUrl":"https:\/\/www.ff-weppersdorf.at\/web\/wp-content\/uploads\/2019\/07\/hlgkuh.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.ff-weppersdorf.at\/web\/20201102-dieselaustritt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.ff-weppersdorf.at\/web\/"},{"@type":"ListItem","position":2,"name":"Diesel ausgelaufen"}]},{"@type":"WebSite","@id":"https:\/\/www.ff-weppersdorf.at\/web\/#website","url":"https:\/\/www.ff-weppersdorf.at\/web\/","name":"Freiwillige Feuerwehr Weppersdorf","description":"News, Eins\u00e4tze &amp; Infos rund um die Freiwillige Feuerwehr Weppersdorf","alternateName":"FF Weppersdorf","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ff-weppersdorf.at\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.ff-weppersdorf.at\/web\/#\/schema\/person\/2580e5c26fdcda22b03944caeac2b379","name":"Jacob Schumann","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/ccaedcfa723205f94f72eb0bd89f8aa426db1f79d3055677333d65c78074d459?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ccaedcfa723205f94f72eb0bd89f8aa426db1f79d3055677333d65c78074d459?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ccaedcfa723205f94f72eb0bd89f8aa426db1f79d3055677333d65c78074d459?s=96&d=mm&r=g","caption":"Jacob Schumann"},"url":"https:\/\/www.ff-weppersdorf.at\/web\/author\/jacob\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ff-weppersdorf.at\/web\/wp-json\/wp\/v2\/posts\/4652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ff-weppersdorf.at\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ff-weppersdorf.at\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ff-weppersdorf.at\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ff-weppersdorf.at\/web\/wp-json\/wp\/v2\/comments?post=4652"}],"version-history":[{"count":1,"href":"https:\/\/www.ff-weppersdorf.at\/web\/wp-json\/wp\/v2\/posts\/4652\/revisions"}],"predecessor-version":[{"id":4653,"href":"https:\/\/www.ff-weppersdorf.at\/web\/wp-json\/wp\/v2\/posts\/4652\/revisions\/4653"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ff-weppersdorf.at\/web\/wp-json\/wp\/v2\/media\/3925"}],"wp:attachment":[{"href":"https:\/\/www.ff-weppersdorf.at\/web\/wp-json\/wp\/v2\/media?parent=4652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ff-weppersdorf.at\/web\/wp-json\/wp\/v2\/categories?post=4652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ff-weppersdorf.at\/web\/wp-json\/wp\/v2\/tags?post=4652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}